{"id":5557,"count":1,"description":"","link":"https:\/\/www.bananaip.com\/intellepedia\/tag\/design-practice\/","name":"Design Practice","slug":"design-practice","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.bananaip.com\/intellepedia\/wp-json\/wp\/v2\/tags\/5557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bananaip.com\/intellepedia\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.bananaip.com\/intellepedia\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.bananaip.com\/intellepedia\/wp-json\/wp\/v2\/posts?tags=5557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}