{"id":1223,"count":0,"description":"","link":"https:\/\/www.bananaip.com\/intellepedia\/tag\/copyight-comics\/","name":"copyight comics","slug":"copyight-comics","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.bananaip.com\/intellepedia\/wp-json\/wp\/v2\/tags\/1223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bananaip.com\/intellepedia\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.bananaip.com\/intellepedia\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.bananaip.com\/intellepedia\/wp-json\/wp\/v2\/posts?tags=1223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}